{"id":4077,"date":"2020-07-29T08:57:27","date_gmt":"2020-07-29T08:57:27","guid":{"rendered":"http:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/?p=4077"},"modified":"2020-07-29T08:57:27","modified_gmt":"2020-07-29T08:57:27","slug":"verkehrssicherheit-am-hvv-busbahnhof-muemmelmannsberg-herstellen","status":"publish","type":"post","link":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/verkehrssicherheit-am-hvv-busbahnhof-muemmelmannsberg-herstellen\/","title":{"rendered":"Verkehrssicherheit am HVV Busbahnhof M\u00fcmmelmannsberg herstellen"},"content":{"rendered":"<p><span style=\"font-size: 14pt; color: #000080;\"><a style=\"color: #000080;\" href=\"http:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/wp-content\/uploads\/2020\/07\/22-0510-Verkehrssicherheit-am-HVV-Busbahnhof-M\u00fcmmelmannsberg-herstellen.pdf\">DOWNLOAD &#8211; Antrag &#8211; Drs.-Nr. 22-0510<\/a><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DOWNLOAD &#8211; Antrag &#8211; Drs.-Nr. 22-0510<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[611,612],"tags":[495,641,665,624],"class_list":["post-4077","post","type-post","status-publish","format-standard","hentry","category-22-wahlperiode-antrage","category-antrage","tag-billstedt","tag-hvv","tag-muemmelmannsberg","tag-verkehr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Verkehrssicherheit am HVV Busbahnhof M\u00fcmmelmannsberg herstellen &#8226; CDU-Bezirksfraktion Hamburg-Mitte<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/verkehrssicherheit-am-hvv-busbahnhof-muemmelmannsberg-herstellen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Verkehrssicherheit am HVV Busbahnhof M\u00fcmmelmannsberg herstellen &#8226; CDU-Bezirksfraktion Hamburg-Mitte\" \/>\n<meta property=\"og:description\" content=\"DOWNLOAD &#8211; Antrag &#8211; Drs.-Nr. 22-0510\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/verkehrssicherheit-am-hvv-busbahnhof-muemmelmannsberg-herstellen\/\" \/>\n<meta property=\"og:site_name\" content=\"CDU-Bezirksfraktion Hamburg-Mitte\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-29T08:57:27+00:00\" \/>\n<meta name=\"author\" content=\"CDU Bezirksfraktion Hamburg-Mitte\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"CDU Bezirksfraktion Hamburg-Mitte\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cdu-fraktion-hamburg-mitte.de\\\/cms\\\/verkehrssicherheit-am-hvv-busbahnhof-muemmelmannsberg-herstellen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cdu-fraktion-hamburg-mitte.de\\\/cms\\\/verkehrssicherheit-am-hvv-busbahnhof-muemmelmannsberg-herstellen\\\/\"},\"author\":{\"name\":\"CDU Bezirksfraktion Hamburg-Mitte\",\"@id\":\"https:\\\/\\\/www.cdu-fraktion-hamburg-mitte.de\\\/cms\\\/#\\\/schema\\\/person\\\/2db16dc65b6e4590ac85c22bd6b0d8bd\"},\"headline\":\"Verkehrssicherheit am HVV Busbahnhof M\u00fcmmelmannsberg herstellen\",\"datePublished\":\"2020-07-29T08:57:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cdu-fraktion-hamburg-mitte.de\\\/cms\\\/verkehrssicherheit-am-hvv-busbahnhof-muemmelmannsberg-herstellen\\\/\"},\"wordCount\":14,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cdu-fraktion-hamburg-mitte.de\\\/cms\\\/#organization\"},\"keywords\":[\"Billstedt\",\"HVV\",\"M\u00fcmmelmannsberg\",\"Verkehr\"],\"articleSection\":[\"22. Wahlperiode\",\"Antr\u00e4ge\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cdu-fraktion-hamburg-mitte.de\\\/cms\\\/verkehrssicherheit-am-hvv-busbahnhof-muemmelmannsberg-herstellen\\\/\",\"url\":\"https:\\\/\\\/www.cdu-fraktion-hamburg-mitte.de\\\/cms\\\/verkehrssicherheit-am-hvv-busbahnhof-muemmelmannsberg-herstellen\\\/\",\"name\":\"Verkehrssicherheit am HVV Busbahnhof M\u00fcmmelmannsberg herstellen &#8226; CDU-Bezirksfraktion Hamburg-Mitte\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cdu-fraktion-hamburg-mitte.de\\\/cms\\\/#website\"},\"datePublished\":\"2020-07-29T08:57:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cdu-fraktion-hamburg-mitte.de\\\/cms\\\/verkehrssicherheit-am-hvv-busbahnhof-muemmelmannsberg-herstellen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cdu-fraktion-hamburg-mitte.de\\\/cms\\\/verkehrssicherheit-am-hvv-busbahnhof-muemmelmannsberg-herstellen\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cdu-fraktion-hamburg-mitte.de\\\/cms\\\/verkehrssicherheit-am-hvv-busbahnhof-muemmelmannsberg-herstellen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.cdu-fraktion-hamburg-mitte.de\\\/cms\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Verkehrssicherheit am HVV Busbahnhof M\u00fcmmelmannsberg herstellen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cdu-fraktion-hamburg-mitte.de\\\/cms\\\/#website\",\"url\":\"https:\\\/\\\/www.cdu-fraktion-hamburg-mitte.de\\\/cms\\\/\",\"name\":\"CDU-Bezirksfraktion Hamburg-Mitte\",\"description\":\"Politik in der Bezirksversammlung Hamburg-Mitte\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cdu-fraktion-hamburg-mitte.de\\\/cms\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cdu-fraktion-hamburg-mitte.de\\\/cms\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cdu-fraktion-hamburg-mitte.de\\\/cms\\\/#organization\",\"name\":\"CDU-B\u00fcrgerschaftsfraktion Hamburg\",\"url\":\"https:\\\/\\\/www.cdu-fraktion-hamburg-mitte.de\\\/cms\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.cdu-fraktion-hamburg-mitte.de\\\/cms\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"CDU-B\u00fcrgerschaftsfraktion Hamburg\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cdu-fraktion-hamburg-mitte.de\\\/cms\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cdu-fraktion-hamburg-mitte.de\\\/cms\\\/#\\\/schema\\\/person\\\/2db16dc65b6e4590ac85c22bd6b0d8bd\",\"name\":\"CDU Bezirksfraktion Hamburg-Mitte\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.cdu-fraktion-hamburg-mitte.de\\\/cms\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/CDU-Logo-Avatar-150x150.png\",\"url\":\"https:\\\/\\\/www.cdu-fraktion-hamburg-mitte.de\\\/cms\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/CDU-Logo-Avatar-150x150.png\",\"contentUrl\":\"https:\\\/\\\/www.cdu-fraktion-hamburg-mitte.de\\\/cms\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/CDU-Logo-Avatar-150x150.png\",\"caption\":\"CDU Bezirksfraktion Hamburg-Mitte\"},\"url\":\"https:\\\/\\\/www.cdu-fraktion-hamburg-mitte.de\\\/cms\\\/author\\\/politikwerft\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Verkehrssicherheit am HVV Busbahnhof M\u00fcmmelmannsberg herstellen &#8226; CDU-Bezirksfraktion Hamburg-Mitte","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/verkehrssicherheit-am-hvv-busbahnhof-muemmelmannsberg-herstellen\/","og_locale":"de_DE","og_type":"article","og_title":"Verkehrssicherheit am HVV Busbahnhof M\u00fcmmelmannsberg herstellen &#8226; CDU-Bezirksfraktion Hamburg-Mitte","og_description":"DOWNLOAD &#8211; Antrag &#8211; Drs.-Nr. 22-0510","og_url":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/verkehrssicherheit-am-hvv-busbahnhof-muemmelmannsberg-herstellen\/","og_site_name":"CDU-Bezirksfraktion Hamburg-Mitte","article_published_time":"2020-07-29T08:57:27+00:00","author":"CDU Bezirksfraktion Hamburg-Mitte","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"CDU Bezirksfraktion Hamburg-Mitte"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/verkehrssicherheit-am-hvv-busbahnhof-muemmelmannsberg-herstellen\/#article","isPartOf":{"@id":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/verkehrssicherheit-am-hvv-busbahnhof-muemmelmannsberg-herstellen\/"},"author":{"name":"CDU Bezirksfraktion Hamburg-Mitte","@id":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/#\/schema\/person\/2db16dc65b6e4590ac85c22bd6b0d8bd"},"headline":"Verkehrssicherheit am HVV Busbahnhof M\u00fcmmelmannsberg herstellen","datePublished":"2020-07-29T08:57:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/verkehrssicherheit-am-hvv-busbahnhof-muemmelmannsberg-herstellen\/"},"wordCount":14,"publisher":{"@id":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/#organization"},"keywords":["Billstedt","HVV","M\u00fcmmelmannsberg","Verkehr"],"articleSection":["22. Wahlperiode","Antr\u00e4ge"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/verkehrssicherheit-am-hvv-busbahnhof-muemmelmannsberg-herstellen\/","url":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/verkehrssicherheit-am-hvv-busbahnhof-muemmelmannsberg-herstellen\/","name":"Verkehrssicherheit am HVV Busbahnhof M\u00fcmmelmannsberg herstellen &#8226; CDU-Bezirksfraktion Hamburg-Mitte","isPartOf":{"@id":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/#website"},"datePublished":"2020-07-29T08:57:27+00:00","breadcrumb":{"@id":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/verkehrssicherheit-am-hvv-busbahnhof-muemmelmannsberg-herstellen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/verkehrssicherheit-am-hvv-busbahnhof-muemmelmannsberg-herstellen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/verkehrssicherheit-am-hvv-busbahnhof-muemmelmannsberg-herstellen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/"},{"@type":"ListItem","position":2,"name":"Verkehrssicherheit am HVV Busbahnhof M\u00fcmmelmannsberg herstellen"}]},{"@type":"WebSite","@id":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/#website","url":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/","name":"CDU-Bezirksfraktion Hamburg-Mitte","description":"Politik in der Bezirksversammlung Hamburg-Mitte","publisher":{"@id":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/#organization","name":"CDU-B\u00fcrgerschaftsfraktion Hamburg","url":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"CDU-B\u00fcrgerschaftsfraktion Hamburg"},"image":{"@id":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/#\/schema\/person\/2db16dc65b6e4590ac85c22bd6b0d8bd","name":"CDU Bezirksfraktion Hamburg-Mitte","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/wp-content\/uploads\/2023\/11\/CDU-Logo-Avatar-150x150.png","url":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/wp-content\/uploads\/2023\/11\/CDU-Logo-Avatar-150x150.png","contentUrl":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/wp-content\/uploads\/2023\/11\/CDU-Logo-Avatar-150x150.png","caption":"CDU Bezirksfraktion Hamburg-Mitte"},"url":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/author\/politikwerft\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/wp-json\/wp\/v2\/posts\/4077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/wp-json\/wp\/v2\/comments?post=4077"}],"version-history":[{"count":0,"href":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/wp-json\/wp\/v2\/posts\/4077\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/wp-json\/wp\/v2\/media?parent=4077"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/wp-json\/wp\/v2\/categories?post=4077"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/wp-json\/wp\/v2\/tags?post=4077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}