{"id":12262,"date":"2022-06-13T11:48:47","date_gmt":"2022-06-13T09:48:47","guid":{"rendered":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/?post_type=tribe_events&#038;p=12262"},"modified":"2022-06-13T11:48:47","modified_gmt":"2022-06-13T09:48:47","slug":"sitzung-des-unterausschusses-bau-fuer-den-regionalausschusses-horn-hamm-borgfelde","status":"publish","type":"tribe_events","link":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/termin\/sitzung-des-unterausschusses-bau-fuer-den-regionalausschusses-horn-hamm-borgfelde\/","title":{"rendered":"Sitzung des Unterausschusses Bau f\u00fcr den Regionalausschusses Horn, Hamm, Borgfelde"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":45,"featured_media":0,"template":"","meta":{"inline_featured_image":false,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-12262","tribe_events","type-tribe_events","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sitzung des Unterausschusses Bau f\u00fcr den Regionalausschusses Horn, Hamm, Borgfelde &#8226; CDU-Bezirksfraktion Hamburg-Mitte<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/termin\/sitzung-des-unterausschusses-bau-fuer-den-regionalausschusses-horn-hamm-borgfelde\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sitzung des Unterausschusses Bau f\u00fcr den Regionalausschusses Horn, Hamm, Borgfelde &#8226; CDU-Bezirksfraktion Hamburg-Mitte\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/termin\/sitzung-des-unterausschusses-bau-fuer-den-regionalausschusses-horn-hamm-borgfelde\/\" \/>\n<meta property=\"og:site_name\" content=\"CDU-Bezirksfraktion Hamburg-Mitte\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cdu-fraktion-hamburg-mitte.de\\\/cms\\\/termin\\\/sitzung-des-unterausschusses-bau-fuer-den-regionalausschusses-horn-hamm-borgfelde\\\/\",\"url\":\"https:\\\/\\\/www.cdu-fraktion-hamburg-mitte.de\\\/cms\\\/termin\\\/sitzung-des-unterausschusses-bau-fuer-den-regionalausschusses-horn-hamm-borgfelde\\\/\",\"name\":\"Sitzung des Unterausschusses Bau f\u00fcr den Regionalausschusses Horn, Hamm, Borgfelde &#8226; CDU-Bezirksfraktion Hamburg-Mitte\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cdu-fraktion-hamburg-mitte.de\\\/cms\\\/#website\"},\"datePublished\":\"2022-06-13T09:48:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cdu-fraktion-hamburg-mitte.de\\\/cms\\\/termin\\\/sitzung-des-unterausschusses-bau-fuer-den-regionalausschusses-horn-hamm-borgfelde\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cdu-fraktion-hamburg-mitte.de\\\/cms\\\/termin\\\/sitzung-des-unterausschusses-bau-fuer-den-regionalausschusses-horn-hamm-borgfelde\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cdu-fraktion-hamburg-mitte.de\\\/cms\\\/termin\\\/sitzung-des-unterausschusses-bau-fuer-den-regionalausschusses-horn-hamm-borgfelde\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.cdu-fraktion-hamburg-mitte.de\\\/cms\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"https:\\\/\\\/www.cdu-fraktion-hamburg-mitte.de\\\/cms\\\/kalender\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sitzung des Unterausschusses Bau f\u00fcr den Regionalausschusses Horn, Hamm, Borgfelde\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cdu-fraktion-hamburg-mitte.de\\\/cms\\\/#website\",\"url\":\"https:\\\/\\\/www.cdu-fraktion-hamburg-mitte.de\\\/cms\\\/\",\"name\":\"CDU-Bezirksfraktion Hamburg-Mitte\",\"description\":\"Politik in der Bezirksversammlung Hamburg-Mitte\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cdu-fraktion-hamburg-mitte.de\\\/cms\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cdu-fraktion-hamburg-mitte.de\\\/cms\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cdu-fraktion-hamburg-mitte.de\\\/cms\\\/#organization\",\"name\":\"CDU-B\u00fcrgerschaftsfraktion Hamburg\",\"url\":\"https:\\\/\\\/www.cdu-fraktion-hamburg-mitte.de\\\/cms\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.cdu-fraktion-hamburg-mitte.de\\\/cms\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"CDU-B\u00fcrgerschaftsfraktion Hamburg\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cdu-fraktion-hamburg-mitte.de\\\/cms\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sitzung des Unterausschusses Bau f\u00fcr den Regionalausschusses Horn, Hamm, Borgfelde &#8226; CDU-Bezirksfraktion Hamburg-Mitte","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/termin\/sitzung-des-unterausschusses-bau-fuer-den-regionalausschusses-horn-hamm-borgfelde\/","og_locale":"de_DE","og_type":"article","og_title":"Sitzung des Unterausschusses Bau f\u00fcr den Regionalausschusses Horn, Hamm, Borgfelde &#8226; CDU-Bezirksfraktion Hamburg-Mitte","og_url":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/termin\/sitzung-des-unterausschusses-bau-fuer-den-regionalausschusses-horn-hamm-borgfelde\/","og_site_name":"CDU-Bezirksfraktion Hamburg-Mitte","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/termin\/sitzung-des-unterausschusses-bau-fuer-den-regionalausschusses-horn-hamm-borgfelde\/","url":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/termin\/sitzung-des-unterausschusses-bau-fuer-den-regionalausschusses-horn-hamm-borgfelde\/","name":"Sitzung des Unterausschusses Bau f\u00fcr den Regionalausschusses Horn, Hamm, Borgfelde &#8226; CDU-Bezirksfraktion Hamburg-Mitte","isPartOf":{"@id":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/#website"},"datePublished":"2022-06-13T09:48:47+00:00","breadcrumb":{"@id":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/termin\/sitzung-des-unterausschusses-bau-fuer-den-regionalausschusses-horn-hamm-borgfelde\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/termin\/sitzung-des-unterausschusses-bau-fuer-den-regionalausschusses-horn-hamm-borgfelde\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/termin\/sitzung-des-unterausschusses-bau-fuer-den-regionalausschusses-horn-hamm-borgfelde\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen","item":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/kalender\/"},{"@type":"ListItem","position":3,"name":"Sitzung des Unterausschusses Bau f\u00fcr den Regionalausschusses Horn, Hamm, Borgfelde"}]},{"@type":"WebSite","@id":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/#website","url":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/","name":"CDU-Bezirksfraktion Hamburg-Mitte","description":"Politik in der Bezirksversammlung Hamburg-Mitte","publisher":{"@id":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/#organization","name":"CDU-B\u00fcrgerschaftsfraktion Hamburg","url":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"CDU-B\u00fcrgerschaftsfraktion Hamburg"},"image":{"@id":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/wp-json\/wp\/v2\/tribe_events\/12262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/wp-json\/wp\/v2\/users\/45"}],"version-history":[{"count":0,"href":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/wp-json\/wp\/v2\/tribe_events\/12262\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/wp-json\/wp\/v2\/media?parent=12262"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/wp-json\/wp\/v2\/tags?post=12262"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.cdu-fraktion-hamburg-mitte.de\/cms\/wp-json\/wp\/v2\/tribe_events_cat?post=12262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}